{"id":152,"date":"2016-01-13T14:42:30","date_gmt":"2016-01-13T17:42:30","guid":{"rendered":"http:\/\/bunkertransportes.com\/?page_id=152"},"modified":"2019-02-05T12:11:46","modified_gmt":"2019-02-05T15:11:46","slug":"furgones-termicos","status":"publish","type":"page","link":"https:\/\/lomva.com.ar\/web\/semirremolques\/furgones-termicos\/","title":{"rendered":"Semirremolques T\u00e9rmicos"},"content":{"rendered":"<p>[vc_row css=\u00bb.vc_custom_1452723756290{margin-bottom: 0px !important;padding-bottom: 0px !important;}\u00bb][vc_column width=\u00bb1\/4&#8243;][vc_widget_sidebar sidebar_id=\u00bbsidebar-1&#8243;][\/vc_column][vc_column width=\u00bb3\/4&#8243;][vc_custom_heading text=\u00bbSTANDARD\u00bb use_theme_fonts=\u00bbyes\u00bb el_class=\u00bbstyle3&#8243;][vc_empty_space height=\u00bb20px\u00bb][vc_images_carousel images=\u00bb499,519,520,521,523&#8243; img_size=\u00bbfull\u00bb autoplay=\u00bbyes\u00bb hide_prev_next_buttons=\u00bbyes\u00bb wrap=\u00bbyes\u00bb][vc_tta_tabs][vc_tta_section title=\u00bbDescripci\u00f3n\u00bb tab_id=\u00bb1452768229038-06ea22f2-31e3d372-4232&#8243;][vc_column_text]Unidad apta para el transporte de productos perecederos. Son similares a los furgones paqueteros, difieren en el revestimiento interior ya que van aisladas con poliuretano expandido. Su estructura es de dise\u00f1o americano, es decir, autoportante de bajo peso, totalmente remachada lo que le otorga la robustez necesaria para una larga vida \u00fatil.[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\u00bbChasis y carrocer\u00eda\u00bb tab_id=\u00bb1452768229135-812a2fe8-2939d372-4232&#8243;][vc_column_text]<strong>Chasis<\/strong><br \/>\nEstructura: autoportante, totalmente remachada.<br \/>\nBandones laterales: Superior e inferior, de aluminio extruido templado.<br \/>\nEstructura bastidor: De chapa de acero. Asiento plato robusto con perno de enganche (King Pin) de acero forjado tratado t\u00e9rmicamente e intercambiable.<br \/>\nSoporte vertical (pata de apoyo): mec\u00e1nica de dos velocidades.<br \/>\nInstalaci\u00f3n de luz y freno: reglamentarias.<\/p>\n<p><strong>Carrocer\u00eda<\/strong><br \/>\nParantes laterales y frente: de chapa galvanizada plegada en forma de galera.<br \/>\nTravesa\u00f1os de techo: en chapa galvanizada plegada.<br \/>\nRevestimiento exterior: En los laterales, frente y puertas, de chapa galvanizada lisa pre- pintada blanca. En el techo, de chapa galvanizada engarfada o aluminio de una sola pieza.<br \/>\nAislaci\u00f3n: Laterales, techo, piso, frente y puertas, inyectados en espuma r\u00edgida de poliuretano expandido. Densidad 40 kg\/m3.<br \/>\nRevestimiento interior: laterales, frente, puertas y techo, en paneles de pl\u00e1stico reforzado con fibra de vidrio, en una sola pieza.<br \/>\nPiso: capa inferior y superior, de madera; aislado en poliuretano expandido.<br \/>\nRevestimiento del piso: en aluminio extruido en forma de canaleta.<br \/>\nOpcional: de chapa galvanizada o acero inoxidable, liso o en canaleta; aluminio plano antideslizante. Z\u00f3calos reforzados de 30cm de alto del material del piso.<br \/>\nMarco trasero: estructura reforzada en chapa de acero plegado, soldado el\u00e9ctricamente, bajo protecci\u00f3n gaseosa.<br \/>\nPuertas traseras: De dos hojas totalmente rebatibles, doble cierre integral y burletes tipo paraguas de cuatro alas.<\/p>\n<p><strong>Pintura<\/strong><br \/>\nEstructura met\u00e1lica desengrasada y fosfatizada.<br \/>\nFondo Epoxi (2 componentes).<br \/>\nEsmalte poliuretano acr\u00edlico (2 componentes).<\/p>\n<p><strong>Opcionales:<\/strong><br \/>\nPuerta lateral con marco de chapa plegada y soldada el\u00e9ctricamente. Hoja totalmente rebatible, con cierre integral y burletes tipo \u201cparaguas\u201d de cuatro alas.[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\u00bbSuspensi\u00f3n y Ejes\u00bb tab_id=\u00bb1452768361593-e6041b7e-836cd372-4232&#8243;][vc_column_text]<strong>Suspensi\u00f3n<\/strong><br \/>\nManotas: estampadas en chapa 3\/16\u2019, con robusto apoyo de el\u00e1sticos.<br \/>\nBalanc\u00edn compensador: de chapa de acero estampada. Perno y bujes de acero tratado t\u00e9rmicamente.<br \/>\nEl\u00e1sticos: semi-el\u00edpticos de 10 hojas graduadas, fabricadas en acero SAE 5160 H.<br \/>\nTensores: fijos y regulables con pernos tratados t\u00e9rmicamente, bujes de acero y goma.<br \/>\nLlantas: (opciones) tipo artillera o discos de 10 agujeros para cubierta con, o sin, c\u00e1mara.<\/p>\n<p><strong>Ejes fijos<\/strong><br \/>\nTubo de eje: redondo de 133 mm. de di\u00e1metro, con pared de 17,5mm. en acero SAE 1037.<br \/>\nPuntas de eje:De acero forjado, tratadas t\u00e9rmicamente.<br \/>\nRuedas: Artilleras de 5 rayos o disco de 10 tornillos, balanceados est\u00e1ticamente.<br \/>\nRodamientos: de tipo \u201cgemelo\u201d, a rodillos c\u00f3nicos, HM 518.445\/410<br \/>\nLubricado: En ba\u00f1o de aceite, SAE 140 o grasa NLGI N\u00ba2 o N\u00ba1.<br \/>\nFreno: de 8\u2019\u2019 para m\u00e1xima exigencia.<br \/>\nPulmones de freno: de c\u00e1mara simple y doble (Spring Brakes) m\u00ednimo en dos ejes, para freno de estacionamiento.<br \/>\nLevas de freno: de acero forjado, tratadas t\u00e9rmicamente.<\/p>\n<p><strong>Eje direccional<\/strong><br \/>\nSuspensi\u00f3n: neum\u00e1tica con levanta eje con aro giratorio.<br \/>\nAlternativa: Eje con sistema auto-direccional. Puntas de eje articuladas con sistema auto-centrante.[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\u00bbAccesorios\u00bb tab_id=\u00bb1452768640148-1bc098d6-3796d372-4232&#8243;][vc_column_text]<strong>Accesorios:<\/strong><br \/>\nPorta-auxilios doble.<br \/>\nCaj\u00f3n para herramientas.<br \/>\nTanque para agua.<br \/>\nParagolpes rebatible con babero.<br \/>\nSemi-guardabarros con pollera de goma.<br \/>\nLlave de rueda.<\/p>\n<p><strong>Opcionales:<\/strong><br \/>\nPuerta lateral con marco de chapa plegada y soldada el\u00e9ctricamente. Hoja totalmente rebatible, con cierre integral y burletes tipo \u201cparaguas\u201d.<br \/>\nEntre piso fijo, con o sin, revestimiento.<br \/>\nTravesa\u00f1os deslizantes con bandejas desmontables.<br \/>\nTravesa\u00f1os de \u201cquita y pon\u201d.<br \/>\nMesa tipo tijera, de accionamiento hidr\u00e1ulico para carga y descarga de entre piso.[\/vc_column_text][\/vc_tta_section][\/vc_tta_tabs][vc_empty_space height=\u00bb20px\u00bb][vc_custom_heading text=\u00bbFRIGOR\u00cdFICO (para cargas refrigeradas colgadas)\u00bb use_theme_fonts=\u00bbyes\u00bb el_class=\u00bbstyle3&#8243;][vc_empty_space height=\u00bb20px\u00bb][vc_images_carousel images=\u00bb499,519,520,521,522&#8243; img_size=\u00bbfull\u00bb autoplay=\u00bbyes\u00bb hide_prev_next_buttons=\u00bbyes\u00bb wrap=\u00bbyes\u00bb][vc_tta_tabs][vc_tta_section title=\u00bbDescripci\u00f3n\u00bb tab_id=\u00bb1452769283600-a45ccf01-65a5d372-4232&#8243;][vc_column_text]Unidades aptas para el transporte de carnes y sus derivados. Son similares a los furgones t\u00e9rmicos con el agregado de rieles para ganchos (gancheras) colocadas en el techo. Su estructura met\u00e1lica totalmente remachada le confiere la robustez que este tipo de transporte requiere lo que la hace la m\u00e1s resistente del mercado.[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\u00bbChasis y carrocer\u00eda\u00bb tab_id=\u00bb1452769283897-8d71e2c6-bbfdd372-4232&#8243;][vc_column_text]<strong>Chasis<\/strong><br \/>\nBandones laterales: Superior e inferior, de aluminio extruido templado.<br \/>\nEstructura bastidor: De chapa de acero. Asiento plato robusto con perno de enganche (King Pin) de acero forjado tratado t\u00e9rmicamente e intercambiable.<br \/>\nParantes laterales y frente: de chapa galvanizada plegada en forma de galera.<br \/>\nTecho: estructura sumamente reforzada con travesa\u00f1os en chapa de 1\/8\u201d de espesor capaces de soportar los 7 rieles de gancheras que posee.<br \/>\nRevestimiento exterior: En los laterales, frente y puertas, de chapa galvanizada lisa pre- pintada blanca. En el techo, de chapa galvanizada engarfada o aluminio de una sola pieza.<br \/>\nAislaci\u00f3n: Laterales, techo, piso, frente y puertas, inyectados en espuma r\u00edgida de poliuretano expandido. Densidad 35 a 40 kg\/m3.<br \/>\nRevestimiento interior: laterales, frente, puertas y techo, en paneles de pl\u00e1stico reforzado con fibra de vidrio, en una sola pieza.<br \/>\nPiso: capa inferior y superior de madera; aislado en poliuretano expandido.<br \/>\nRevestimiento del piso: en aluminio extruido en forma de canaleta. Opcional: de chapa galvanizada o acero inoxidable, liso o en canaleta; aluminio plano antideslizante. Z\u00f3calos reforzados de 30cm de alto del material del piso.<br \/>\nMarco trasero: estructura reforzada en chapa de acero plegado, soldado el\u00e9ctricamente, bajo protecci\u00f3n gaseosa.<br \/>\nPuertas traseras: De dos hojas totalmente rebatibles, doble cierre integral y burletes tipo paraguas de cuatro alas.<br \/>\nSoporte vertical (pata de apoyo): mec\u00e1nica de dos velocidades.<br \/>\nInstalaci\u00f3n de luz y freno: reglamentarias.<\/p>\n<p><strong>Pintura<\/strong><br \/>\nEstructura met\u00e1lica desengrasada y fosfatizada.<br \/>\nFondo Epoxi (2 componentes).<br \/>\nEsmalte poliuretano acr\u00edlico (2 componentes).<\/p>\n<p><strong>Opcionales:<\/strong><br \/>\nPuerta lateral con marco de chapa plegada y soldada el\u00e9ctricamente. Hoja totalmente rebatible, con cierre integral y burletes tipo \u201cparaguas\u201d de cuatro alas.[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\u00bbSuspensi\u00f3n y Ejes\u00bb tab_id=\u00bb1452769284200-81430a2e-1754d372-4232&#8243;][vc_column_text]<strong>Suspensi\u00f3n<\/strong><br \/>\nManotas: estampadas en chapa 3\/16\u2019, con robusto apoyo de el\u00e1sticos.<br \/>\nBalanc\u00edn compensador: de chapa de acero estampada. Perno y bujes de acero tratado t\u00e9rmicamente<br \/>\nEl\u00e1sticos: semi-el\u00edpticos de 10 hojas graduadas, fabricadas en acero SAE 5160 H.<br \/>\nTensores: fijos y regulables con pernos tratados t\u00e9rmicamente, bujes de acero y goma.<br \/>\nLlantas: (opciones) tipo artillera o discos de 10 agujeros para cubierta con, o sin, c\u00e1mara.<\/p>\n<p><strong>Ejes fijos<\/strong><br \/>\nTubo de eje: redondo de 133 mm. de di\u00e1metro, con pared de 17,5mm. en acero SAE 1037.<br \/>\nPuntas de eje: De acero forjado, tratadas t\u00e9rmicamente.<br \/>\nRuedas: Artilleras de 5 rayos o disco de 10 tornillos, balanceados est\u00e1ticamente.<br \/>\nRodamientos: de tipo \u201cgemelo\u201d, a rodillos c\u00f3nicos, HM 518.445\/410<br \/>\nLubricado: En ba\u00f1o de aceite, SAE 140 o grasa NLGI N\u00ba2 o N\u00ba1.<br \/>\nFreno: de 8\u2019\u2019 para m\u00e1xima exigencia.<br \/>\nPulmones de freno: de c\u00e1mara simple y doble (Spring Brakes) m\u00ednimo en dos ejes, para freno de estacionamiento.<br \/>\nLevas de freno: de acero forjado, tratadas t\u00e9rmicamente.<\/p>\n<p><strong>Eje direccional<\/strong><br \/>\nSuspensi\u00f3n: neum\u00e1tica con levanta eje con aro giratorio.<br \/>\nAlternativa: Eje con sistema auto-direccional. Puntas de eje articuladas con sistema auto-centrante[\/vc_column_text][\/vc_tta_section][vc_tta_section title=\u00bbAccesorios\u00bb tab_id=\u00bb1452769284525-9c15f506-1784d372-4232&#8243;][vc_column_text]<strong>Accesorios:<\/strong><br \/>\nPorta- auxilios doble.<br \/>\nCaj\u00f3n para herramientas.<br \/>\nTanque para agua.<br \/>\nParagolpes rebatible con babero.<br \/>\nSemi-guardabarros con pollera de goma.<br \/>\nLlave de rueda.<br \/>\n205 ganchos.<br \/>\nPuerta lateral con marco de chapa plegada y soldada el\u00e9ctricamente. Hoja totalmente rebatible, con cierre integral y burletes tipo \u201cparaguas\u201d.<br \/>\nEntre piso fijo, con o sin, revestimiento.<br \/>\nTravesa\u00f1os deslizantes con bandejas desmontables.<br \/>\nTravesa\u00f1os de \u201cquita y pon\u201d.<br \/>\nMesa tipo tijera, de accionamiento hidr\u00e1ulico para carga y descarga de entre piso.[\/vc_column_text][\/vc_tta_section][\/vc_tta_tabs][vc_empty_space height=\u00bb20px\u00bb][vc_row_inner equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb css=\u00bb.vc_custom_1452728831104{padding-top: 20px !important;padding-right: 20px !important;padding-bottom: 20px !important;padding-left: 20px !important;background-color: #eeeeee !important;border-radius: 5px !important;}\u00bb][vc_column_inner width=\u00bb1\/4&#8243; css=\u00bb.vc_custom_1452728614968{padding-top: 0px !important;}\u00bb][vc_custom_heading text=\u00bbREPRESENTANTE OFICIAL\u00bb font_container=\u00bbtag:h3|text_align:left\u00bb use_theme_fonts=\u00bbyes\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243; css=\u00bb.vc_custom_1452728623057{padding-top: 0px !important;}\u00bb][vc_single_image image=\u00bb314&#8243; img_size=\u00bbfull\u00bb alignment=\u00bbcenter\u00bb css=\u00bb.vc_custom_1452767378464{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243; css=\u00bb.vc_custom_1452767341336{padding-top: 0px !important;}\u00bb][\/vc_column_inner][vc_column_inner width=\u00bb1\/4&#8243; css=\u00bb.vc_custom_1452767349987{padding-top: 0px !important;}\u00bb][vc_single_image image=\u00bb316&#8243; img_size=\u00bbfull\u00bb alignment=\u00bbcenter\u00bb css=\u00bb.vc_custom_1452767402529{margin-top: 0px !important;margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00bb][\/vc_column_inner][\/vc_row_inner][vc_row_inner][vc_column_inner width=\u00bb2\/3&#8243;][vc_custom_heading text=\u00bbCONSULTE POR ESTE PRODUCTO\u00bb use_theme_fonts=\u00bbyes\u00bb el_class=\u00bbstyle3&#8243;][vc_empty_space height=\u00bb20px\u00bb][vc_column_text css=\u00bb.vc_custom_1452724919034{margin-top: 0px !important;margin-bottom: 15px !important;padding-top: 0px !important;padding-bottom: 0px !important;}\u00bb]Eavac\u00fae sus dudas con respectoa este producto. \u00a0Estamos para asesorarlo y brindarle la mejor atenci\u00f3n.[\/vc_column_text]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f220-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"220\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/web\/wp-json\/wp\/v2\/pages\/152#wpcf7-f220-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"220\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f220-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p class=\"ozy-half-input\"><span class=\"wpcf7-form-control-wrap\" data-name=\"nombre\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Su Nombre y Apellido *\" value=\"\" type=\"text\" name=\"nombre\" \/><\/span>\n<\/p>\n<p class=\"ozy-half-input-last\"><span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Su Email *\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n<\/p>\n<p class=\"ozy-half-input\"><span class=\"wpcf7-form-control-wrap\" data-name=\"telefono\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Su Tel\u00e9fono *\" value=\"\" type=\"text\" name=\"telefono\" \/><\/span>\n<\/p>\n<p class=\"ozy-half-input-last\"><span class=\"wpcf7-form-control-wrap\" data-name=\"localidad\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Su Localidad *\" value=\"\" type=\"text\" name=\"localidad\" \/><\/span>\n<\/p>\n<p class=\"ozy-full-input\"><span class=\"wpcf7-form-control-wrap\" data-name=\"consulta\"><textarea cols=\"40\" rows=\"8\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Detallenos su Consulta...\" name=\"consulta\"><\/textarea><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"ENVIAR CONSULTA\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"210\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/vc_column_inner][vc_column_inner width=\u00bb1\/3&#8243;][vc_single_image image=\u00bb221&#8243; img_size=\u00bbfull\u00bb alignment=\u00bbcenter\u00bb css=\u00bb.vc_custom_1452723809882{margin-bottom: 0px !important;padding-bottom: 0px !important;}\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row css=\u00bb.vc_custom_1452723756290{margin-bottom: 0px !important;padding-bottom: 0px !important;}\u00bb][vc_column width=\u00bb1\/4&#8243;][vc_widget_sidebar sidebar_id=\u00bbsidebar-1&#8243;][\/vc_column][vc_column width=\u00bb3\/4&#8243;][vc_custom_heading text=\u00bbSTANDARD\u00bb use_theme_fonts=\u00bbyes\u00bb el_class=\u00bbstyle3&#8243;][vc_empty_space height=\u00bb20px\u00bb][vc_images_carousel images=\u00bb499,519,520,521,523&#8243; img_size=\u00bbfull\u00bb autoplay=\u00bbyes\u00bb hide_prev_next_buttons=\u00bbyes\u00bb wrap=\u00bbyes\u00bb][vc_tta_tabs][vc_tta_section title=\u00bbDescripci\u00f3n\u00bb tab_id=\u00bb1452768229038-06ea22f2-31e3d372-4232&#8243;][vc_column_text]Unidad [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":536,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-152","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/lomva.com.ar\/web\/wp-json\/wp\/v2\/pages\/152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lomva.com.ar\/web\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lomva.com.ar\/web\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lomva.com.ar\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lomva.com.ar\/web\/wp-json\/wp\/v2\/comments?post=152"}],"version-history":[{"count":0,"href":"https:\/\/lomva.com.ar\/web\/wp-json\/wp\/v2\/pages\/152\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/lomva.com.ar\/web\/wp-json\/wp\/v2\/pages\/536"}],"wp:attachment":[{"href":"https:\/\/lomva.com.ar\/web\/wp-json\/wp\/v2\/media?parent=152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}